{"id":9070,"date":"2016-08-17T20:24:03","date_gmt":"2016-08-17T23:24:03","guid":{"rendered":"http:\/\/amensagem.org\/home\/wp-content\/uploads\/2016\/08\/GardensByTheBay-31.jpg"},"modified":"2016-08-17T20:24:25","modified_gmt":"2016-08-17T23:24:25","slug":"gardensbythebay-31","status":"inherit","type":"attachment","link":"http:\/\/amensagem.org\/home\/gardensbythebay-31\/","title":{"rendered":"crentes mimados e plantas de estufa"},"author":1,"comment_status":"open","ping_status":"closed","template":"","meta":[],"description":{"rendered":"<p class=\"attachment\"><a href='http:\/\/amensagem.org\/home\/wp-content\/uploads\/2016\/08\/GardensByTheBay-31.jpg'><img width=\"300\" height=\"125\" src=\"http:\/\/amensagem.org\/home\/wp-content\/uploads\/2016\/08\/GardensByTheBay-31-300x125.jpg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"http:\/\/amensagem.org\/home\/wp-content\/uploads\/2016\/08\/GardensByTheBay-31-300x125.jpg 300w, http:\/\/amensagem.org\/home\/wp-content\/uploads\/2016\/08\/GardensByTheBay-31-768x320.jpg 768w, http:\/\/amensagem.org\/home\/wp-content\/uploads\/2016\/08\/GardensByTheBay-31-1024x427.jpg 1024w, http:\/\/amensagem.org\/home\/wp-content\/uploads\/2016\/08\/GardensByTheBay-31.jpg 1152w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1152,"height":480,"file":"2016\/08\/GardensByTheBay-31.jpg","sizes":{"thumbnail":{"file":"GardensByTheBay-31-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"http:\/\/amensagem.org\/home\/wp-content\/uploads\/2016\/08\/GardensByTheBay-31-150x150.jpg"},"medium":{"file":"GardensByTheBay-31-300x125.jpg","width":300,"height":125,"mime_type":"image\/jpeg","source_url":"http:\/\/amensagem.org\/home\/wp-content\/uploads\/2016\/08\/GardensByTheBay-31-300x125.jpg"},"medium_large":{"file":"GardensByTheBay-31-768x320.jpg","width":768,"height":320,"mime_type":"image\/jpeg","source_url":"http:\/\/amensagem.org\/home\/wp-content\/uploads\/2016\/08\/GardensByTheBay-31-768x320.jpg"},"large":{"file":"GardensByTheBay-31-1024x427.jpg","width":1024,"height":427,"mime_type":"image\/jpeg","source_url":"http:\/\/amensagem.org\/home\/wp-content\/uploads\/2016\/08\/GardensByTheBay-31-1024x427.jpg"},"post-thumbnail":{"file":"GardensByTheBay-31-720x380.jpg","width":720,"height":380,"mime_type":"image\/jpeg","source_url":"http:\/\/amensagem.org\/home\/wp-content\/uploads\/2016\/08\/GardensByTheBay-31-720x380.jpg"},"vantage-thumbnail-no-sidebar":{"file":"GardensByTheBay-31-1080x380.jpg","width":1080,"height":380,"mime_type":"image\/jpeg","source_url":"http:\/\/amensagem.org\/home\/wp-content\/uploads\/2016\/08\/GardensByTheBay-31-1080x380.jpg"},"vantage-slide":{"file":"GardensByTheBay-31-960x480.jpg","width":960,"height":480,"mime_type":"image\/jpeg","source_url":"http:\/\/amensagem.org\/home\/wp-content\/uploads\/2016\/08\/GardensByTheBay-31-960x480.jpg"},"vantage-carousel":{"file":"GardensByTheBay-31-272x182.jpg","width":272,"height":182,"mime_type":"image\/jpeg","source_url":"http:\/\/amensagem.org\/home\/wp-content\/uploads\/2016\/08\/GardensByTheBay-31-272x182.jpg"},"vantage-grid-loop":{"file":"GardensByTheBay-31-436x272.jpg","width":436,"height":272,"mime_type":"image\/jpeg","source_url":"http:\/\/amensagem.org\/home\/wp-content\/uploads\/2016\/08\/GardensByTheBay-31-436x272.jpg"},"sow-carousel-default":{"file":"GardensByTheBay-31-272x182.jpg","width":272,"height":182,"mime_type":"image\/jpeg","source_url":"http:\/\/amensagem.org\/home\/wp-content\/uploads\/2016\/08\/GardensByTheBay-31-272x182.jpg"},"full":{"file":"GardensByTheBay-31.jpg","width":1152,"height":480,"mime_type":"image\/jpeg","source_url":"http:\/\/amensagem.org\/home\/wp-content\/uploads\/2016\/08\/GardensByTheBay-31.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"http:\/\/amensagem.org\/home\/wp-content\/uploads\/2016\/08\/GardensByTheBay-31.jpg","_links":{"self":[{"href":"http:\/\/amensagem.org\/home\/wp-json\/wp\/v2\/media\/9070"}],"collection":[{"href":"http:\/\/amensagem.org\/home\/wp-json\/wp\/v2\/media"}],"about":[{"href":"http:\/\/amensagem.org\/home\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"http:\/\/amensagem.org\/home\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/amensagem.org\/home\/wp-json\/wp\/v2\/comments?post=9070"}]}}